{"id":19029,"date":"2023-11-08T10:48:37","date_gmt":"2023-11-08T10:48:37","guid":{"rendered":"https:\/\/hokutoryu.com\/black-belts\/3-dan\/"},"modified":"2025-12-30T14:26:29","modified_gmt":"2025-12-30T14:26:29","slug":"3-dan","status":"publish","type":"page","link":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/","title":{"rendered":"3 DAN"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"19029\" class=\"elementor elementor-19029 elementor-14147\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d936c4 elementor-section-full_width elementor-section-stretched animated-slow elementor-section-height-default elementor-section-height-default\" data-id=\"7d936c4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac0e703\" data-id=\"ac0e703\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86c352e elementor-widget elementor-widget-global elementor-global-5495 elementor-widget-ucaddon_simple_slider\" data-id=\"86c352e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"ucaddon_simple_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Simple Slider -->\n\t\t<link id='font-awesome-css' href='https:\/\/hokutoryu.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/hokutoryu.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='uc_ac_assets_file_slick_css_1729-css' href='https:\/\/hokutoryu.com\/wp-content\/uploads\/ac_assets\/simple_animated_slider\/slick.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Simple Slider *\/\n\n#uc_simple_slider_elementor_86c352e\n{\n  overflow:hidden;\n  direction:ltr;\n}\n#uc_simple_slider_elementor_86c352e .ue_slide {\n  position: relative;\n}\n#uc_simple_slider_elementor_86c352e .slide__img {\n  width: 100%;\n  height: auto;\n  overflow: hidden;\n}\n\n#uc_simple_slider_elementor_86c352e .slide__img img {\n  max-width: 100%;\n  height: auto;\n  opacity: 1 !important;          \n  animation-duration: 3s;\n  transition: all 1s ease;\n}\n#uc_simple_slider_elementor_86c352e .slide__content {\n  position: absolute;\n  top: 50%;\n  left: 50%;\n  transform: translate(-50%, -50%);\n}\n#uc_simple_slider_elementor_86c352e .slide__content--headings {\n  text-align: center;\n  color: #FFF;\n}\n#uc_simple_slider_elementor_86c352e .slide__content--headings h2 {\n}\n#uc_simple_slider_elementor_86c352e .slide__content--headings .animated {\n  transition: all 0.5s ease;\n}\n.ue_simple_slider_title\n{\n  font-size:26px;\n}\n\n#uc_simple_slider_elementor_86c352e .ue_simple_slider_button a{\n\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n}  \n\n\n#uc_simple_slider_elementor_86c352e .slick-prev{\n    position:absolute;\n    left:0px;\n    display:flex !important;\n    align-items:center;\n    justify-content:center;\n    text-align:center;\n    z-index:101;\n    border:none;\n    outline:none;\n}\n#uc_simple_slider_elementor_86c352e .slick-next{\n  position:absolute;\n  right:0px;\n  display:flex !important;\n  align-items:center;\n    justify-content:center;\n  text-align:center;\n  z-index:101;\n  border:none;\n  outline:none;\n}\n\n#uc_simple_slider_elementor_86c352e .ue_slide_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n}\n\n#uc_simple_slider_elementor_86c352e .ue_slide_link_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n  display:block;\n  z-index:1;\n}\n\n.slick-dotted.slick-slider\n{\n  margin-bottom:0px !important;\n}\n\n\n\n\n.slick-dots {\n  position: absolute;\n  list-style: none;\n  display: block;\n  text-align: center;\n  padding: 0;\n  margin: 0;\n  width: 100%;\n  z-index:2;\n}\n.slick-dots li {\n  position: relative;\n  display: inline-block;\n  margin: 0 5px;\n  padding: 0;\n  cursor: pointer;\n}\n.slick-dots li button {\n  border: 0;\n  display: block;\n  outline: none;\n  line-height: 0px;\n  font-size: 0px;\n  color: transparent;\n  padding: 5px;\n  cursor: pointer;\n  transition: all 0.3s ease;\n}\n.slick-dots li button:hover,\n.slick-dots li button:focus {\n  outline: none;\n}\n.simple-dots .slick-dots li {\n\n}\n.simple-dots .slick-dots li button {\n  border-radius: 50%;\n}\n\n.stick-dots .slick-dots li button {\n  position: relative;\n  padding: 0;\n}\n\n<\/style>\n\n<div class=\"ue_slider stick-dots\" id=\"uc_simple_slider_elementor_86c352e\" >\n    <div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_header.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu1.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu2.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu3.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu4.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu5.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu6.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu7_uusi.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu8.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu9.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n\n<\/div>\n<!-- end Simple Slider -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b22739b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b22739b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d273e1\" data-id=\"4d273e1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25cf43b elementor-nav-menu__align-center elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"25cf43b\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-25cf43b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19317\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/1-dan\/\" class=\"elementor-item\">1 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19318\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/2-dan\/\" class=\"elementor-item\">2 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19319\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\" class=\"elementor-item\">3 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19320\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/4-dan\/\" class=\"elementor-item\">4 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19321\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/5-dan\/\" class=\"elementor-item\">5 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19322\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/\" class=\"elementor-item\">Highest Master Ranks<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-25cf43b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19317\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/1-dan\/\" class=\"elementor-item\" tabindex=\"-1\">1 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19318\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/2-dan\/\" class=\"elementor-item\" tabindex=\"-1\">2 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19319\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\" class=\"elementor-item\" tabindex=\"-1\">3 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19320\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/4-dan\/\" class=\"elementor-item\" tabindex=\"-1\">4 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19321\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/5-dan\/\" class=\"elementor-item\" tabindex=\"-1\">5 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19322\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/\" class=\"elementor-item\" tabindex=\"-1\">Highest Master Ranks<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61da3e9 elementor-section-height-min-height elementor-section-stretched animated-slow elementor-section-items-top elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"61da3e9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3494ebd\" data-id=\"3494ebd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6b3915d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6b3915d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-aea0ad6\" data-id=\"aea0ad6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89ab9f2 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"89ab9f2\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_89ab9f2 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_89ab9f2\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/04\/tariqalyasin-kopio.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Alyasin Tariq<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c273477\" data-id=\"c273477\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5a1893a elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"5a1893a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_5a1893a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_5a1893a\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Bj\u00f6rkqvist Andreas<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b4ded94\" data-id=\"b4ded94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-03401da elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"03401da\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_03401da .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_03401da\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Florstr\u00f6m Kaj<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-dc3c42d\" data-id=\"dc3c42d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a77ea9 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"1a77ea9\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_1a77ea9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_1a77ea9\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/haanpaaheidi3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Haanp\u00e4\u00e4 Heidi<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-98909ee elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98909ee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4b401f8\" data-id=\"4b401f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6d3d29 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"c6d3d29\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_c6d3d29 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_c6d3d29\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/04\/tuomohari-kopio.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Hari Tuomo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5080a63\" data-id=\"5080a63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf7f805 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"cf7f805\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_cf7f805 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_cf7f805\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Hattuniemi Asko<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-92899bb\" data-id=\"92899bb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12eb0fd elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"12eb0fd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_12eb0fd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_12eb0fd\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/04\/janihellsten-kopio.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Hellsten Jani<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-240300e\" data-id=\"240300e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0984791 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"0984791\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_0984791 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_0984791\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/11\/huttunenkari_3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Huttunen Kari<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2454afa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2454afa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-da93ccf\" data-id=\"da93ccf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d67e3f elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"9d67e3f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_9d67e3f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_9d67e3f\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Jankola-V\u00e4nt\u00e4r Nina<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-76fe337\" data-id=\"76fe337\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6ca76a elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"b6ca76a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_b6ca76a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_b6ca76a\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Johansson Mikael <\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7ff4792\" data-id=\"7ff4792\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf61f1b elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"bf61f1b\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_bf61f1b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_bf61f1b\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Kangas Pertti<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d32ca83\" data-id=\"d32ca83\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7c754b elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"d7c754b\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_d7c754b .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_d7c754b\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Katajam\u00e4ki Pekka<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f62ae31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f62ae31\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-7a7adcb\" data-id=\"7a7adcb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b802e43 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"b802e43\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_b802e43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_b802e43\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/kujanpaajesse1dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Kujanp\u00e4\u00e4 Jesse<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-32562f3\" data-id=\"32562f3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5788691 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"5788691\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_5788691 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_5788691\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Kuprina Irina<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f498b52\" data-id=\"f498b52\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e34135a elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"e34135a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_e34135a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_e34135a\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/04\/anssilindqvist-kopio.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Lindqvist Anssi<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-631f5e5\" data-id=\"631f5e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1f18b1 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"a1f18b1\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_a1f18b1 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_a1f18b1\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Magamedova Alexandra<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1c107f6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c107f6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-1794dab\" data-id=\"1794dab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4436b8 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"e4436b8\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_e4436b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_e4436b8\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Malinen Harri<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9ea8ba4\" data-id=\"9ea8ba4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-415c689 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"415c689\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_415c689 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_415c689\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Mustakallio Petri<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-c00e357\" data-id=\"c00e357\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-103cdee elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"103cdee\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_103cdee .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_103cdee\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/paakkinenpetri3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Paakkinen Petri<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e9a6259\" data-id=\"e9a6259\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d3a49d elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"7d3a49d\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_7d3a49d .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_7d3a49d\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/04\/mattipihlava-kopio.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Pihlava Matti<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2c8e0cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c8e0cd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-4a396d6\" data-id=\"4a396d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-046a7de elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"046a7de\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_046a7de .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_046a7de\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/purmonentimo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Purmonen Timo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-81ad0fb\" data-id=\"81ad0fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7defc84 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"7defc84\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_7defc84 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_7defc84\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/riekkolaannaleena3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Riekkola Anna-Leena<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8b173ee\" data-id=\"8b173ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70bdadd elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"70bdadd\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_70bdadd .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_70bdadd\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Rissanen Pasi<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-105cd13\" data-id=\"105cd13\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89a2e8f elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"89a2e8f\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_89a2e8f .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_89a2e8f\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/ruotsalainentoni3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Ruotsalainen Toni<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6e5614e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e5614e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-30868b0\" data-id=\"30868b0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0079b8 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"b0079b8\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_b0079b8 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_b0079b8\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/11\/saarikoskimichael_3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Saarikoski Michael<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e47a6d5\" data-id=\"e47a6d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b4d146 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"6b4d146\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_6b4d146 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_6b4d146\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Saarinen Mika<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-805acc2\" data-id=\"805acc2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c972dc elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"7c972dc\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_7c972dc .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_7c972dc\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2025\/04\/sipolajanne_3dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Sipola Janne<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-fb604be\" data-id=\"fb604be\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-40119e5 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"40119e5\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_40119e5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_40119e5\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Tapio Visa<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a28882a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a28882a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-f95ce6c\" data-id=\"f95ce6c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f0cb8b7 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"f0cb8b7\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_f0cb8b7 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_f0cb8b7\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/tenhunenjarmo2dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Tenhunen Jarmo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-00a9a12\" data-id=\"00a9a12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-082240a elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"082240a\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_082240a .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_082240a\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/mustavyo.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Virta Pasi<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>3. DAN<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-d3c7272\" data-id=\"d3c7272\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-42eb6f1\" data-id=\"42eb6f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-646f62e elementor-widget elementor-widget-spacer\" data-id=\"646f62e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-978ae56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"978ae56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe762ab\" data-id=\"fe762ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-724cb23 elementor-widget elementor-widget-template\" data-id=\"724cb23\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"5527\" class=\"elementor elementor-5527\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dce85cb elementor-section-height-min-height elementor-section-stretched animated-slow elementor-section-items-top elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"3dce85cb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-592e1671\" data-id=\"592e1671\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e82f865 elementor-widget elementor-widget-text-editor\" data-id=\"6e82f865\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5><span style=\"color: #ffffff;\"><span style=\"font-size: 22.8px;\">Hokutoryu HQ<\/span><\/span><\/h5>\n<p>Puh: <a href=\"tel:+35896946554\">09 694 6554<\/a>&nbsp;<i>(arkisin 13-20)<\/i><br>S\u00e4hk\u00f6posti:&nbsp;<a href=\"mailto:info@hokutoryu.com\">info@hokutoryu.com<\/a><br>Tallberginkatu 1 D 59<br>00180 Helsinki<\/p>\n<h5><a href=\"https:\/\/hokutoryu.com\/kotimaiset-seurat\/\"><span style=\"color: #ffffff;\">L\u00f6yd\u00e4 l\u00e4hin Hokutoryuseura<\/span><\/a><\/h5>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-29dfcf78\" data-id=\"29dfcf78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83c21ed elementor-widget elementor-widget-image\" data-id=\"83c21ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"639\" height=\"400\" src=\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider.png\" class=\"attachment-large size-large wp-image-19593\" alt=\"\" srcset=\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider.png 639w, https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider-300x188.png 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-198f64e1\" data-id=\"198f64e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aecff7d elementor-widget elementor-widget-heading\" data-id=\"aecff7d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Some<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd7859e elementor-widget elementor-widget-ucaddon_social_icons_glare_effect\" data-id=\"4fd7859e\" data-element_type=\"widget\" data-widget_type=\"ucaddon_social_icons_glare_effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Social Icons Glare Effect -->\n\n<style>\/* widget: Social Icons Glare Effect *\/\n\n#uc_social_icons_glare_effect_elementor_4fd7859e *{\n\n\tbox-sizing: border-box;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e{\n\tposition:relative;\n\twidth:100%;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button {\n    box-shadow: 0 0 30px 0 rgba(0, 0, 0, 0.05);\n    display: inline-block;\n    opacity: 1;\n    overflow: hidden;\n    position: relative;\n    text-align: center;\n    transition: all 0.35s cubic-bezier(0.31, -0.105, 0.43, 1.59) 0s;\n    \n}\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button::before {\n    content: \"\";\n    height: 100%;\n    left: 0%;\n    position: absolute;\n    top: 100%;\n    transition: all 0.35s;\n    width: 100%;\n}\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button i {\n    transform: scale(0.8);\n    transition: all 0.35s cubic-bezier(0.31, -0.105, 0.43, 1.59) 0s;\n    vertical-align: middle;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button:focus::before, \n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button:hover::before {\n    left: 0%;\n    top: 0%;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button i {\n\tcolor:#000000;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button:hover i {\n\tcolor:#ffffff;\n}\n\n<\/style>\n\n<div class=\"uc_stylish_social_buttons\" id=\"uc_social_icons_glare_effect_elementor_4fd7859e\"> \n    <!--uc_container_holder--> \n    <div class=\"uc_social-buttons\">\n    \t<a href=\"https:\/\/www.facebook.com\/hokutoryu\/\" class=\"uc_social-button\"  ><i class=\"fab fa-facebook\"><\/i><\/a>\n<a href=\"https:\/\/www.instagram.com\/jujutsuworld\/\" class=\"uc_social-button\"  ><i class=\"fab fa-instagram\"><\/i><\/a>\n\n    <\/div>\n<\/div>\n<!-- end Social Icons Glare Effect -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Alyasin Tariq 3. DAN Bj\u00f6rkqvist Andreas 3. DAN Florstr\u00f6m Kaj 3. DAN Haanp\u00e4\u00e4 Heidi 3. DAN Hari Tuomo 3. DAN Hattuniemi Asko 3. DAN Hellsten Jani 3. DAN Huttunen Kari 3. DAN Jankola-V\u00e4nt\u00e4r Nina 3. DAN Johansson Mikael 3. DAN Kangas Pertti 3. DAN Katajam\u00e4ki Pekka 3. DAN Kujanp\u00e4\u00e4 Jesse 3. DAN Kuprina Irina 3. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":18977,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-19029","page","type-page","status-publish","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>3 DAN - Hokutoryu ju-jutsu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 DAN - Hokutoryu ju-jutsu\" \/>\n<meta property=\"og:description\" content=\"Alyasin Tariq 3. DAN Bj\u00f6rkqvist Andreas 3. DAN Florstr\u00f6m Kaj 3. DAN Haanp\u00e4\u00e4 Heidi 3. DAN Hari Tuomo 3. DAN Hattuniemi Asko 3. DAN Hellsten Jani 3. DAN Huttunen Kari 3. DAN Jankola-V\u00e4nt\u00e4r Nina 3. DAN Johansson Mikael 3. DAN Kangas Pertti 3. DAN Katajam\u00e4ki Pekka 3. DAN Kujanp\u00e4\u00e4 Jesse 3. DAN Kuprina Irina 3. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\" \/>\n<meta property=\"og:site_name\" content=\"Hokutoryu ju-jutsu\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T14:26:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\",\"url\":\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\",\"name\":\"3 DAN - Hokutoryu ju-jutsu\",\"isPartOf\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/#website\"},\"datePublished\":\"2023-11-08T10:48:37+00:00\",\"dateModified\":\"2025-12-30T14:26:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hokutoryu.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Highest Master Ranks\",\"item\":\"https:\/\/hokutoryu.com\/en\/black-belts\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"3 DAN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hokutoryu.com\/en\/#website\",\"url\":\"https:\/\/hokutoryu.com\/en\/\",\"name\":\"Hokutoryu ju-jutsu\",\"description\":\"Northern style, founder Soke Auvo Niiniketo \",\"publisher\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hokutoryu.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hokutoryu.com\/en\/#organization\",\"name\":\"Helsingin ju-jutsuklubi\",\"url\":\"https:\/\/hokutoryu.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg\",\"contentUrl\":\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg\",\"width\":2048,\"height\":1448,\"caption\":\"Helsingin ju-jutsuklubi\"},\"image\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 DAN - Hokutoryu ju-jutsu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/","og_locale":"en_US","og_type":"article","og_title":"3 DAN - Hokutoryu ju-jutsu","og_description":"Alyasin Tariq 3. DAN Bj\u00f6rkqvist Andreas 3. DAN Florstr\u00f6m Kaj 3. DAN Haanp\u00e4\u00e4 Heidi 3. DAN Hari Tuomo 3. DAN Hattuniemi Asko 3. DAN Hellsten Jani 3. DAN Huttunen Kari 3. DAN Jankola-V\u00e4nt\u00e4r Nina 3. DAN Johansson Mikael 3. DAN Kangas Pertti 3. DAN Katajam\u00e4ki Pekka 3. DAN Kujanp\u00e4\u00e4 Jesse 3. DAN Kuprina Irina 3. [&hellip;]","og_url":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/","og_site_name":"Hokutoryu ju-jutsu","article_modified_time":"2025-12-30T14:26:29+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/","url":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/","name":"3 DAN - Hokutoryu ju-jutsu","isPartOf":{"@id":"https:\/\/hokutoryu.com\/en\/#website"},"datePublished":"2023-11-08T10:48:37+00:00","dateModified":"2025-12-30T14:26:29+00:00","breadcrumb":{"@id":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hokutoryu.com\/en\/"},{"@type":"ListItem","position":2,"name":"Highest Master Ranks","item":"https:\/\/hokutoryu.com\/en\/black-belts\/"},{"@type":"ListItem","position":3,"name":"3 DAN"}]},{"@type":"WebSite","@id":"https:\/\/hokutoryu.com\/en\/#website","url":"https:\/\/hokutoryu.com\/en\/","name":"Hokutoryu ju-jutsu","description":"Northern style, founder Soke Auvo Niiniketo ","publisher":{"@id":"https:\/\/hokutoryu.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hokutoryu.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hokutoryu.com\/en\/#organization","name":"Helsingin ju-jutsuklubi","url":"https:\/\/hokutoryu.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg","contentUrl":"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg","width":2048,"height":1448,"caption":"Helsingin ju-jutsuklubi"},"image":{"@id":"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/19029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/comments?post=19029"}],"version-history":[{"count":1,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/19029\/revisions"}],"predecessor-version":[{"id":19049,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/19029\/revisions\/19049"}],"up":[{"embeddable":true,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/18977"}],"wp:attachment":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/media?parent=19029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}