{"id":18977,"date":"2023-09-11T12:21:52","date_gmt":"2023-09-11T12:21:52","guid":{"rendered":"https:\/\/hokutoryu.com\/black-belts\/"},"modified":"2025-12-30T14:13:36","modified_gmt":"2025-12-30T14:13:36","slug":"black-belts","status":"publish","type":"page","link":"https:\/\/hokutoryu.com\/en\/black-belts\/","title":{"rendered":"Highest Master Ranks"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"18977\" class=\"elementor elementor-18977 elementor-5436\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d936c4 elementor-section-full_width elementor-section-stretched animated-slow elementor-section-height-default elementor-section-height-default\" data-id=\"7d936c4\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac0e703\" data-id=\"ac0e703\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-86c352e elementor-widget elementor-widget-global elementor-global-5495 elementor-widget-ucaddon_simple_slider\" data-id=\"86c352e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;none&quot;}\" data-widget_type=\"ucaddon_simple_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Simple Slider -->\n\t\t<link id='font-awesome-css' href='https:\/\/hokutoryu.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-all.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='font-awesome-4-shim-css' href='https:\/\/hokutoryu.com\/wp-content\/plugins\/unlimited-elements-for-elementor\/assets_libraries\/font-awesome6\/fontawesome-v4-shims.min.css' type='text\/css' rel='stylesheet' >\n\t\t<link id='uc_ac_assets_file_slick_css_1729-css' href='https:\/\/hokutoryu.com\/wp-content\/uploads\/ac_assets\/simple_animated_slider\/slick.css' type='text\/css' rel='stylesheet' >\n\n<style>\/* widget: Simple Slider *\/\n\n#uc_simple_slider_elementor_86c352e\n{\n  overflow:hidden;\n  direction:ltr;\n}\n#uc_simple_slider_elementor_86c352e .ue_slide {\n  position: relative;\n}\n#uc_simple_slider_elementor_86c352e .slide__img {\n  width: 100%;\n  height: auto;\n  overflow: hidden;\n}\n\n#uc_simple_slider_elementor_86c352e .slide__img img {\n  max-width: 100%;\n  height: auto;\n  opacity: 1 !important;          \n  animation-duration: 3s;\n  transition: all 1s ease;\n}\n#uc_simple_slider_elementor_86c352e .slide__content {\n  position: absolute;\n  top: 50%;\n  left: 50%;\n  transform: translate(-50%, -50%);\n}\n#uc_simple_slider_elementor_86c352e .slide__content--headings {\n  text-align: center;\n  color: #FFF;\n}\n#uc_simple_slider_elementor_86c352e .slide__content--headings h2 {\n}\n#uc_simple_slider_elementor_86c352e .slide__content--headings .animated {\n  transition: all 0.5s ease;\n}\n.ue_simple_slider_title\n{\n  font-size:26px;\n}\n\n#uc_simple_slider_elementor_86c352e .ue_simple_slider_button a{\n\n  display:inline-block;\n  text-align:center;\n  text-decoration:none;\n}  \n\n\n#uc_simple_slider_elementor_86c352e .slick-prev{\n    position:absolute;\n    left:0px;\n    display:flex !important;\n    align-items:center;\n    justify-content:center;\n    text-align:center;\n    z-index:101;\n    border:none;\n    outline:none;\n}\n#uc_simple_slider_elementor_86c352e .slick-next{\n  position:absolute;\n  right:0px;\n  display:flex !important;\n  align-items:center;\n    justify-content:center;\n  text-align:center;\n  z-index:101;\n  border:none;\n  outline:none;\n}\n\n#uc_simple_slider_elementor_86c352e .ue_slide_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n}\n\n#uc_simple_slider_elementor_86c352e .ue_slide_link_overlay\n{\n  position:absolute;\n  top:0;\n  bottom:0;\n  left:0;\n  right:0;\n  display:block;\n  z-index:1;\n}\n\n.slick-dotted.slick-slider\n{\n  margin-bottom:0px !important;\n}\n\n\n\n\n.slick-dots {\n  position: absolute;\n  list-style: none;\n  display: block;\n  text-align: center;\n  padding: 0;\n  margin: 0;\n  width: 100%;\n  z-index:2;\n}\n.slick-dots li {\n  position: relative;\n  display: inline-block;\n  margin: 0 5px;\n  padding: 0;\n  cursor: pointer;\n}\n.slick-dots li button {\n  border: 0;\n  display: block;\n  outline: none;\n  line-height: 0px;\n  font-size: 0px;\n  color: transparent;\n  padding: 5px;\n  cursor: pointer;\n  transition: all 0.3s ease;\n}\n.slick-dots li button:hover,\n.slick-dots li button:focus {\n  outline: none;\n}\n.simple-dots .slick-dots li {\n\n}\n.simple-dots .slick-dots li button {\n  border-radius: 50%;\n}\n\n.stick-dots .slick-dots li button {\n  position: relative;\n  padding: 0;\n}\n\n<\/style>\n\n<div class=\"ue_slider stick-dots\" id=\"uc_simple_slider_elementor_86c352e\" >\n    <div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_header.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu1.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu2.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu3.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu4.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu5.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu6.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu7_uusi.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu8.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu9.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n<div class=\"ue_slide\" style=\"background-image:url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu.png);background-size:cover;background-position:center center;\">\n  <div class=\"ue_slide_overlay\"><\/div>  \n     \n      <div class=\"slide__content\" style=\"position:relative; z-index:1;\">\n        <div class=\"slide__content--headings\">\n           <div class=\"ue_simple_slider_title\"><\/div>           <div class=\"ue_simple_slider_text\"><\/div>                   <\/div>\n      <\/div>\n          \n<\/div>\n\n<\/div>\n<!-- end Simple Slider -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b22739b elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b22739b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d273e1\" data-id=\"4d273e1\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25cf43b elementor-nav-menu__align-center elementor-nav-menu__text-align-center elementor-nav-menu--dropdown-tablet elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"25cf43b\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;horizontal&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas fa-caret-down\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-solid&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t<nav class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-horizontal e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-25cf43b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19317\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/1-dan\/\" class=\"elementor-item\">1 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19318\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/2-dan\/\" class=\"elementor-item\">2 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19319\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\" class=\"elementor-item\">3 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19320\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/4-dan\/\" class=\"elementor-item\">4 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19321\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/5-dan\/\" class=\"elementor-item\">5 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19322\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/\" class=\"elementor-item\">Highest Master Ranks<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-25cf43b\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19317\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/1-dan\/\" class=\"elementor-item\" tabindex=\"-1\">1 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19318\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/2-dan\/\" class=\"elementor-item\" tabindex=\"-1\">2 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19319\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/3-dan\/\" class=\"elementor-item\" tabindex=\"-1\">3 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19320\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/4-dan\/\" class=\"elementor-item\" tabindex=\"-1\">4 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19321\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/5-dan\/\" class=\"elementor-item\" tabindex=\"-1\">5 DAN<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-19322\"><a href=\"https:\/\/hokutoryu.com\/en\/black-belts\/\" class=\"elementor-item\" tabindex=\"-1\">Highest Master Ranks<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61da3e9 elementor-section-height-min-height elementor-section-stretched animated-slow elementor-section-items-top elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"61da3e9\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3494ebd\" data-id=\"3494ebd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3633cac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3633cac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0e4c041\" data-id=\"0e4c041\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-d8467bc\" data-id=\"d8467bc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f455ec4 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"f455ec4\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_f455ec4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_f455ec4\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/sokeniiniketo-1.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Niiniketo Auvo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>10. DAN<br>Developer of Hokutoryu.<\/p><\/div>\t\t\t\t\t\t<a  href=\"\" class=\"uc_btn\" >Introduction<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f5e6c1b\" data-id=\"f5e6c1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b2e0c96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2e0c96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e20c5e5\" data-id=\"e20c5e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5b4d3fc\" data-id=\"5b4d3fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c6c56ef elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"c6c56ef\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_c6c56ef .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_c6c56ef\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hirvonentimo8dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Hirvonen Timo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>8. DAN<br>Hanshi<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/hokutoryu.com\/mustat-vyot\/timo-hirvonen\/\" class=\"uc_btn\" >Introduction<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-6e76e00\" data-id=\"6e76e00\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a857b5 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"8a857b5\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_8a857b5 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_8a857b5\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/vantarristo8dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">V\u00e4nt\u00e4r Risto<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>8. DAN<br>Hanshi<\/p><\/div>\t\t\t\t\t\t<a  href=\"https:\/\/hokutoryu.com\/mustat-vyot\/risto-vantar\/\" class=\"uc_btn\" >Introduction<\/a>                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-063f43a\" data-id=\"063f43a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5b45939 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b45939\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9562e98\" data-id=\"9562e98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8494939 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"8494939\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_8494939 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_8494939\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/tenhunenkimmo7dan-s.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Tenhunen Kimmo<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>7. DAN<br>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-8d17b11\" data-id=\"8d17b11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73246e9 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"73246e9\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_73246e9 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_73246e9\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2024\/06\/andreiambros-1.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Ambros Andrei<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>6. DAN<\/p><p>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0ba32d5\" data-id=\"0ba32d5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4973b6e elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"4973b6e\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_4973b6e .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_4973b6e\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/kabritsjaak5dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Kabrits Jaak<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>6. DAN<\/p><p>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b6df5c2\" data-id=\"b6df5c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b2b294 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"4b2b294\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_4b2b294 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_4b2b294\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/koivistotero5dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Koivisto Tero<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>6. DAN<br>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-84b2589 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84b2589\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-02ad087\" data-id=\"02ad087\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-34e12e4 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"34e12e4\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_34e12e4 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_34e12e4\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/korotkikhevgeny.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Korotkikh Evgeny<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>6. DAN<br>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-432a37b\" data-id=\"432a37b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c46257 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"3c46257\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_3c46257 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_3c46257\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/lehtonenkari6dan.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Lehtonen Kari<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>6. DAN<\/p><p>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cba2b57\" data-id=\"cba2b57\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e0cd43 elementor-widget elementor-widget-ucaddon_hover_text_reveal_content_box\" data-id=\"4e0cd43\" data-element_type=\"widget\" data-widget_type=\"ucaddon_hover_text_reveal_content_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Content Box Hover Text Reveal -->\n<style>\/* widget: Content Box Hover Text Reveal *\/\n\n.uc_long_content_box {\n\toverflow:hidden;\n}\n.uc_long_content_box *{\n\tbox-sizing: border-box;\n}\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder{\n\tposition: relative;\n    text-align:left;\n    overflow:hidden;\n}\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box{\n\tposition: relative;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_image_box{\n\tposition: relative;\n\tbackground-size: cover !important;\n\tbackground-repeat: no-repeat !important;\n\tbackground-position: center center !important;\n\twidth: 100%;\n    background-blend-mode:normal;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_overlay{\n\tposition: absolute;\n\tleft: 0;\n\ttop: 0;\n    right:0;\n    bottom:0;\n\twidth: 100%;\n\theight: 100%;\n\tz-index: 2;\n  transition:1s;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content{\n\tleft: 0;\n    bottom: 0;\n    position: absolute;\n    margin: 0;\n    width: 100%;\n\tz-index: 3;\n\toverflow: hidden;\n\tdisplay: flex;\n    height: 100%;\n    flex-direction: column;\n    justify-content: flex-end;\n}\n\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_title{\n  transition:0.5s;\t\n}\n\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content {\n  transition:0.5s;\n  transform: translateY(10px);\n}\n.uc_title\n{\n    font-weight: 400;\n\tfont-size: 22px;\n}\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_title{\n  transform: translateY(-10px);\t\n}\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n\toverflow: hidden;\n    transform: scaleY(0);\n    transform-origin: bottom;\n  transition:0.5s;\n    max-height: 0;\n\topacity: 0;\n}\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder:hover .uc_long_content_box_box .uc_box_content .uc_hidden_content{\n    max-height: 100%;\n    transform: scaleY(1);\n    overflow: visible;\n\topacity: 1;\n\t\n}\n\n.uc_box_content .uc_description{\n\tcolor: #fff;\n}\n#uc_hover_text_reveal_content_box_elementor_4e0cd43 .uc_long_content_box_holder .uc_long_content_box_box .uc_box_content .uc_btn{\n\ttext-decoration: none;\n\tdisplay: inline-block;\n    text-align:center;\n  transition:0.5s;\n}\n\n<\/style>\n\n<div class=\"uc_long_content_box\" id=\"uc_hover_text_reveal_content_box_elementor_4e0cd43\">\n\t\t<div class=\"uc_long_content_box_holder\">\n\t\t\t\n\t\t\t<div class=\"uc_long_content_box_box\">\n\t\t\t\t<div class=\"uc_image_box\" style=\" background-image: url(https:\/\/hokutoryu.com\/wp-content\/uploads\/2025\/02\/ottarv-1.jpg);\"><\/div>\n\t\t\t\t<div class=\"uc_overlay\" ><\/div>\n\t\t\t\t<div class=\"uc_box_content\">\n\t\t\t\t\t<div class=\"uc_title\">Vassenden Ottar<\/div>\t\t\t\t\t<div class=\"uc_hidden_content\">\n\t\t\t\t\t\t<div class=\"uc_description\"><p>6. DAN<br>Shihan<\/p><\/div>\t\t\t\t\t\t                        \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n    <\/div>\n<!-- end Content Box Hover Text Reveal -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-20bb7c2\" data-id=\"20bb7c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-646f62e elementor-widget elementor-widget-spacer\" data-id=\"646f62e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-978ae56 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"978ae56\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fe762ab\" data-id=\"fe762ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-724cb23 elementor-widget elementor-widget-template\" data-id=\"724cb23\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"5527\" class=\"elementor elementor-5527\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3dce85cb elementor-section-height-min-height elementor-section-stretched animated-slow elementor-section-items-top elementor-section-boxed elementor-section-height-default elementor-invisible\" data-id=\"3dce85cb\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wider\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-592e1671\" data-id=\"592e1671\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e82f865 elementor-widget elementor-widget-text-editor\" data-id=\"6e82f865\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5><span style=\"color: #ffffff;\"><span style=\"font-size: 22.8px;\">Hokutoryu HQ<\/span><\/span><\/h5>\n<p>Puh: <a href=\"tel:+35896946554\">09 694 6554<\/a>&nbsp;<i>(arkisin 13-20)<\/i><br>S\u00e4hk\u00f6posti:&nbsp;<a href=\"mailto:info@hokutoryu.com\">info@hokutoryu.com<\/a><br>Tallberginkatu 1 D 59<br>00180 Helsinki<\/p>\n<h5><a href=\"https:\/\/hokutoryu.com\/kotimaiset-seurat\/\"><span style=\"color: #ffffff;\">L\u00f6yd\u00e4 l\u00e4hin Hokutoryuseura<\/span><\/a><\/h5>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-29dfcf78\" data-id=\"29dfcf78\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83c21ed elementor-widget elementor-widget-image\" data-id=\"83c21ed\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"639\" height=\"400\" src=\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider.png\" class=\"attachment-large size-large wp-image-19593\" alt=\"\" srcset=\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider.png 639w, https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/11\/hokutoryu_slaider-300x188.png 300w\" sizes=\"(max-width: 639px) 100vw, 639px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-198f64e1\" data-id=\"198f64e1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-aecff7d elementor-widget elementor-widget-heading\" data-id=\"aecff7d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h5 class=\"elementor-heading-title elementor-size-default\">Some<\/h5>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fd7859e elementor-widget elementor-widget-ucaddon_social_icons_glare_effect\" data-id=\"4fd7859e\" data-element_type=\"widget\" data-widget_type=\"ucaddon_social_icons_glare_effect.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n<!-- start Social Icons Glare Effect -->\n\n<style>\/* widget: Social Icons Glare Effect *\/\n\n#uc_social_icons_glare_effect_elementor_4fd7859e *{\n\n\tbox-sizing: border-box;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e{\n\tposition:relative;\n\twidth:100%;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button {\n    box-shadow: 0 0 30px 0 rgba(0, 0, 0, 0.05);\n    display: inline-block;\n    opacity: 1;\n    overflow: hidden;\n    position: relative;\n    text-align: center;\n    transition: all 0.35s cubic-bezier(0.31, -0.105, 0.43, 1.59) 0s;\n    \n}\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button::before {\n    content: \"\";\n    height: 100%;\n    left: 0%;\n    position: absolute;\n    top: 100%;\n    transition: all 0.35s;\n    width: 100%;\n}\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button i {\n    transform: scale(0.8);\n    transition: all 0.35s cubic-bezier(0.31, -0.105, 0.43, 1.59) 0s;\n    vertical-align: middle;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button:focus::before, \n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button:hover::before {\n    left: 0%;\n    top: 0%;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button i {\n\tcolor:#000000;\n}\n\n#uc_social_icons_glare_effect_elementor_4fd7859e .uc_social-button:hover i {\n\tcolor:#ffffff;\n}\n\n<\/style>\n\n<div class=\"uc_stylish_social_buttons\" id=\"uc_social_icons_glare_effect_elementor_4fd7859e\"> \n    <!--uc_container_holder--> \n    <div class=\"uc_social-buttons\">\n    \t<a href=\"https:\/\/www.facebook.com\/hokutoryu\/\" class=\"uc_social-button\"  ><i class=\"fab fa-facebook\"><\/i><\/a>\n<a href=\"https:\/\/www.instagram.com\/jujutsuworld\/\" class=\"uc_social-button\"  ><i class=\"fab fa-instagram\"><\/i><\/a>\n\n    <\/div>\n<\/div>\n<!-- end Social Icons Glare Effect -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Niiniketo Auvo 10. DANDeveloper of Hokutoryu. Introduction Hirvonen Timo 8. DANHanshi Introduction V\u00e4nt\u00e4r Risto 8. DANHanshi Introduction Tenhunen Kimmo 7. DANShihan Ambros Andrei 6. DAN Shihan Kabrits Jaak 6. DAN Shihan Koivisto Tero 6. DANShihan Korotkikh Evgeny 6. DANShihan Lehtonen Kari 6. DAN Shihan Vassenden Ottar 6. DANShihan<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-18977","page","type-page","status-publish","czr-hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Highest Master Ranks - Hokutoryu ju-jutsu<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hokutoryu.com\/en\/black-belts\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Highest Master Ranks - Hokutoryu ju-jutsu\" \/>\n<meta property=\"og:description\" content=\"Niiniketo Auvo 10. DANDeveloper of Hokutoryu. Introduction Hirvonen Timo 8. DANHanshi Introduction V\u00e4nt\u00e4r Risto 8. DANHanshi Introduction Tenhunen Kimmo 7. DANShihan Ambros Andrei 6. DAN Shihan Kabrits Jaak 6. DAN Shihan Koivisto Tero 6. DANShihan Korotkikh Evgeny 6. DANShihan Lehtonen Kari 6. DAN Shihan Vassenden Ottar 6. DANShihan\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hokutoryu.com\/en\/black-belts\/\" \/>\n<meta property=\"og:site_name\" content=\"Hokutoryu ju-jutsu\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-30T14:13:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/hokutoryu.com\/en\/black-belts\/\",\"url\":\"https:\/\/hokutoryu.com\/en\/black-belts\/\",\"name\":\"Highest Master Ranks - Hokutoryu ju-jutsu\",\"isPartOf\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/#website\"},\"datePublished\":\"2023-09-11T12:21:52+00:00\",\"dateModified\":\"2025-12-30T14:13:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/black-belts\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/hokutoryu.com\/en\/black-belts\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/hokutoryu.com\/en\/black-belts\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/hokutoryu.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Highest Master Ranks\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/hokutoryu.com\/en\/#website\",\"url\":\"https:\/\/hokutoryu.com\/en\/\",\"name\":\"Hokutoryu ju-jutsu\",\"description\":\"Northern style, founder Soke Auvo Niiniketo \",\"publisher\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/hokutoryu.com\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/hokutoryu.com\/en\/#organization\",\"name\":\"Helsingin ju-jutsuklubi\",\"url\":\"https:\/\/hokutoryu.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg\",\"contentUrl\":\"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg\",\"width\":2048,\"height\":1448,\"caption\":\"Helsingin ju-jutsuklubi\"},\"image\":{\"@id\":\"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Highest Master Ranks - Hokutoryu ju-jutsu","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hokutoryu.com\/en\/black-belts\/","og_locale":"en_US","og_type":"article","og_title":"Highest Master Ranks - Hokutoryu ju-jutsu","og_description":"Niiniketo Auvo 10. DANDeveloper of Hokutoryu. Introduction Hirvonen Timo 8. DANHanshi Introduction V\u00e4nt\u00e4r Risto 8. DANHanshi Introduction Tenhunen Kimmo 7. DANShihan Ambros Andrei 6. DAN Shihan Kabrits Jaak 6. DAN Shihan Koivisto Tero 6. DANShihan Korotkikh Evgeny 6. DANShihan Lehtonen Kari 6. DAN Shihan Vassenden Ottar 6. DANShihan","og_url":"https:\/\/hokutoryu.com\/en\/black-belts\/","og_site_name":"Hokutoryu ju-jutsu","article_modified_time":"2025-12-30T14:13:36+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hokutoryu.com\/en\/black-belts\/","url":"https:\/\/hokutoryu.com\/en\/black-belts\/","name":"Highest Master Ranks - Hokutoryu ju-jutsu","isPartOf":{"@id":"https:\/\/hokutoryu.com\/en\/#website"},"datePublished":"2023-09-11T12:21:52+00:00","dateModified":"2025-12-30T14:13:36+00:00","breadcrumb":{"@id":"https:\/\/hokutoryu.com\/en\/black-belts\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hokutoryu.com\/en\/black-belts\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/hokutoryu.com\/en\/black-belts\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hokutoryu.com\/en\/"},{"@type":"ListItem","position":2,"name":"Highest Master Ranks"}]},{"@type":"WebSite","@id":"https:\/\/hokutoryu.com\/en\/#website","url":"https:\/\/hokutoryu.com\/en\/","name":"Hokutoryu ju-jutsu","description":"Northern style, founder Soke Auvo Niiniketo ","publisher":{"@id":"https:\/\/hokutoryu.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hokutoryu.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/hokutoryu.com\/en\/#organization","name":"Helsingin ju-jutsuklubi","url":"https:\/\/hokutoryu.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg","contentUrl":"https:\/\/hokutoryu.com\/wp-content\/uploads\/2023\/06\/14976325_1168686479835207_7750700877726327082_o.jpeg","width":2048,"height":1448,"caption":"Helsingin ju-jutsuklubi"},"image":{"@id":"https:\/\/hokutoryu.com\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/18977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/comments?post=18977"}],"version-history":[{"count":3,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/18977\/revisions"}],"predecessor-version":[{"id":19013,"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/pages\/18977\/revisions\/19013"}],"wp:attachment":[{"href":"https:\/\/hokutoryu.com\/en\/wp-json\/wp\/v2\/media?parent=18977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}